{"id":5438,"date":"2020-10-11T16:47:08","date_gmt":"2020-10-11T15:47:08","guid":{"rendered":"http:\/\/quelaines-stemarie.fr\/?p=5438"},"modified":"2020-10-11T16:47:09","modified_gmt":"2020-10-11T15:47:09","slug":"seances-de-musique-cm1-cm2","status":"publish","type":"post","link":"http:\/\/quelaines-stemarie.fr\/index.php\/2020\/10\/11\/seances-de-musique-cm1-cm2\/","title":{"rendered":"S\u00e9ances de musique CM1-CM2"},"content":{"rendered":"\n<p>Depuis plusieurs semaines, Anne vient \u00e0 l&#8217;\u00e9cole pour nous faire chanter. Les chansons choisies sont \u00e9galement apprises par les r\u00e9sidents de la r\u00e9sidence autonomie Le Mottais. Quand la situation sanitaire le permettra, nous esp\u00e9rons pouvoir nous rencontrer et chanter ensemble.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-1024x576.jpg\" alt=\"\" data-id=\"5439\" data-full-url=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-scaled.jpg\" data-link=\"http:\/\/quelaines-stemarie.fr\/?attachment_id=5439\" class=\"wp-image-5439\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-1024x576.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-300x169.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-768x432.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-1536x864.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-2048x1152.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/IMG_0647-150x84.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-rich is-provider-prise-en-charge-des-contenus-embarques wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"IMG 0649\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/6wKkvjb2HRE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Depuis plusieurs semaines, Anne vient \u00e0 l&#8217;\u00e9cole pour nous faire chanter. Les chansons choisies sont \u00e9galement apprises par les r\u00e9sidents de la r\u00e9sidence autonomie Le Mottais. Quand la situation sanitaire le permettra, nous esp\u00e9rons pouvoir nous rencontrer et chanter ensemble.<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"http:\/\/quelaines-stemarie.fr\/index.php\/2020\/10\/11\/seances-de-musique-cm1-cm2\/\">Lire la suite&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":5,"featured_media":5439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,59],"tags":[],"class_list":["post-5438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cat-actualites","category-cat-cm1cm2-2016"],"_links":{"self":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/5438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5438"}],"version-history":[{"count":1,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/5438\/revisions"}],"predecessor-version":[{"id":5441,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/5438\/revisions\/5441"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/5439"}],"wp:attachment":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5438"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}