{"id":8380,"date":"2022-06-22T22:50:11","date_gmt":"2022-06-22T21:50:11","guid":{"rendered":"http:\/\/quelaines-stemarie.fr\/?p=8380"},"modified":"2022-09-24T09:05:16","modified_gmt":"2022-09-24T08:05:16","slug":"arts-visuels-en-ce-cm-periode-5","status":"publish","type":"post","link":"http:\/\/quelaines-stemarie.fr\/index.php\/2022\/06\/22\/arts-visuels-en-ce-cm-periode-5\/","title":{"rendered":"Arts Visuels en CE-CM (P\u00e9riode 5)"},"content":{"rendered":"\n<p>L&#8217;ann\u00e9e scolaire touche \u00e0 sa fin. Voici les derni\u00e8res r\u00e9alisations de cette p\u00e9riode.<\/p>\n\n\n\n<p>Travail sur les d\u00e9grad\u00e9s de couleurs:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"723\" data-id=\"8382\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-1024x723.jpg\" alt=\"\" class=\"wp-image-8382\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-1024x723.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-300x212.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-768x542.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-1536x1084.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-2048x1446.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-3-150x106.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"704\" data-id=\"8383\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-1024x704.jpg\" alt=\"\" class=\"wp-image-8383\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-1024x704.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-300x206.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-768x528.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-1536x1056.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-2048x1408.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-6-150x103.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"719\" data-id=\"8381\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-1024x719.jpg\" alt=\"\" class=\"wp-image-8381\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-1024x719.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-300x211.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-768x539.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-1536x1078.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-2048x1438.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Ours-geometrique-Degrades-de-couleurs-8-150x105.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"731\" height=\"1024\" data-id=\"8384\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-731x1024.jpg\" alt=\"\" class=\"wp-image-8384\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-731x1024.jpg 731w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-214x300.jpg 214w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-768x1075.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-1097x1536.jpg 1097w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-1463x2048.jpg 1463w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-107x150.jpg 107w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-1-scaled.jpg 1828w\" sizes=\"auto, (max-width: 731px) 100vw, 731px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" data-id=\"8385\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-721x1024.jpg\" alt=\"\" class=\"wp-image-8385\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-721x1024.jpg 721w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-211x300.jpg 211w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-768x1090.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-1082x1536.jpg 1082w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-1443x2048.jpg 1443w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-106x150.jpg 106w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-2-scaled.jpg 1804w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"1024\" data-id=\"8386\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-719x1024.jpg\" alt=\"\" class=\"wp-image-8386\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-719x1024.jpg 719w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-211x300.jpg 211w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-768x1093.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-1079x1536.jpg 1079w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-1438x2048.jpg 1438w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-105x150.jpg 105w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Degrades-de-couleurs-7-scaled.jpg 1798w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"706\" height=\"1024\" data-id=\"8387\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-706x1024.jpg\" alt=\"\" class=\"wp-image-8387\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-706x1024.jpg 706w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-207x300.jpg 207w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-768x1114.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-1059x1536.jpg 1059w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-1412x2048.jpg 1412w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-103x150.jpg 103w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-4-scaled.jpg 1765w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"707\" height=\"1024\" data-id=\"8389\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-707x1024.jpg\" alt=\"\" class=\"wp-image-8389\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-707x1024.jpg 707w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-207x300.jpg 207w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-768x1112.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-1061x1536.jpg 1061w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-1414x2048.jpg 1414w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-104x150.jpg 104w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-6-scaled.jpg 1768w\" sizes=\"auto, (max-width: 707px) 100vw, 707px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"716\" height=\"1024\" data-id=\"8390\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-716x1024.jpg\" alt=\"\" class=\"wp-image-8390\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-716x1024.jpg 716w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-210x300.jpg 210w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-768x1099.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-1074x1536.jpg 1074w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-1432x2048.jpg 1432w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-105x150.jpg 105w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Animaux-geometriques-Degrades-de-couleurs-5-scaled.jpg 1789w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Travail sur les couleurs compl\u00e9mentaires:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"701\" data-id=\"8391\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-1024x701.jpg\" alt=\"\" class=\"wp-image-8391\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-1024x701.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-300x205.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-768x525.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-1536x1051.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-2048x1401.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-5-150x103.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" data-id=\"8392\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-1024x707.jpg\" alt=\"\" class=\"wp-image-8392\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-1024x707.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-300x207.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-768x530.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-1536x1061.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-2048x1414.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Couleurs-complementaires-7-150x104.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"670\" data-id=\"8393\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-1024x670.jpg\" alt=\"\" class=\"wp-image-8393\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-1024x670.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-300x196.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-768x503.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-1536x1005.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-2048x1341.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Couleurs-complementaires-1-150x98.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Travail sur les nuances de bleu + d\u00e9couverte de l&#8217;artiste Aldemir Martins:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"1024\" data-id=\"8394\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-796x1024.jpg\" alt=\"\" class=\"wp-image-8394\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-796x1024.jpg 796w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-233x300.jpg 233w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-768x988.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-1193x1536.jpg 1193w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-1591x2048.jpg 1591w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-117x150.jpg 117w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-1-scaled.jpg 1989w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"1024\" data-id=\"8400\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-763x1024.jpg\" alt=\"\" class=\"wp-image-8400\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-763x1024.jpg 763w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-223x300.jpg 223w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-768x1031.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-1144x1536.jpg 1144w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-1525x2048.jpg 1525w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-112x150.jpg 112w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-7-scaled.jpg 1906w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"777\" height=\"1024\" data-id=\"8405\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-777x1024.jpg\" alt=\"\" class=\"wp-image-8405\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-777x1024.jpg 777w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-228x300.jpg 228w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-768x1012.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-1166x1536.jpg 1166w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-1554x2048.jpg 1554w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-114x150.jpg 114w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Chat-Aldemir-MARTINS-9-scaled.jpg 1943w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>D\u00e9couverte de l&#8217;artiste Vassily Kandinsky, avec diff\u00e9rentes &#8220;\u00e9tudes de couleurs&#8221;:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"713\" height=\"1024\" data-id=\"8406\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-713x1024.jpg\" alt=\"\" class=\"wp-image-8406\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-713x1024.jpg 713w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-209x300.jpg 209w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-768x1103.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-1070x1536.jpg 1070w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-1426x2048.jpg 1426w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-104x150.jpg 104w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-2-scaled.jpg 1783w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"1024\" data-id=\"8407\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-736x1024.jpg\" alt=\"\" class=\"wp-image-8407\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-736x1024.jpg 736w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-216x300.jpg 216w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-768x1068.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-1104x1536.jpg 1104w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-1472x2048.jpg 1472w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-108x150.jpg 108w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-3-scaled.jpg 1840w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"1024\" data-id=\"8408\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-719x1024.jpg\" alt=\"\" class=\"wp-image-8408\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-719x1024.jpg 719w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-211x300.jpg 211w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-768x1094.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-1078x1536.jpg 1078w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-1437x2048.jpg 1437w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-105x150.jpg 105w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Celine-Arbre-a-la-maniere-de-Kandinsky-6-scaled.jpg 1797w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"8409\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-768x1024.jpg\" alt=\"\" class=\"wp-image-8409\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-768x1024.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-225x300.jpg 225w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-1152x1536.jpg 1152w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-1536x2048.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-113x150.jpg 113w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE1-Sylvie-Collectif-Etude-de-couleurs-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1011\" data-id=\"8410\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-1024x1011.jpg\" alt=\"\" class=\"wp-image-8410\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-1024x1011.jpg 1024w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-300x296.jpg 300w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-768x758.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-1536x1517.jpg 1536w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-2048x2022.jpg 2048w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Collectif-Etude-de-couleurs-carres-avec-cercles-concentriques-150x148.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1005\" height=\"1024\" data-id=\"8411\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-1005x1024.jpg\" alt=\"\" class=\"wp-image-8411\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-1005x1024.jpg 1005w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-294x300.jpg 294w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-768x783.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-1507x1536.jpg 1507w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-2010x2048.jpg 2010w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM1-Etudes-de-couleurs-6-147x150.jpg 147w\" sizes=\"auto, (max-width: 1005px) 100vw, 1005px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1009\" height=\"1024\" data-id=\"8412\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-1009x1024.jpg\" alt=\"\" class=\"wp-image-8412\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-1009x1024.jpg 1009w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-296x300.jpg 296w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-768x780.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-1513x1536.jpg 1513w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-2017x2048.jpg 2017w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-5-148x150.jpg 148w\" sizes=\"auto, (max-width: 1009px) 100vw, 1009px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1024\" data-id=\"8413\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-1000x1024.jpg\" alt=\"\" class=\"wp-image-8413\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-1000x1024.jpg 1000w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-293x300.jpg 293w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-768x786.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-1500x1536.jpg 1500w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-2000x2048.jpg 2000w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CM2-Etudes-de-couleurs-8-146x150.jpg 146w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>D\u00e9couverte de l&#8217;Art Aborig\u00e8ne:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"830\" height=\"1024\" data-id=\"8469\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-830x1024.jpg\" alt=\"\" class=\"wp-image-8469\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-830x1024.jpg 830w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-243x300.jpg 243w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-768x948.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-1245x1536.jpg 1245w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-1659x2048.jpg 1659w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-7-1-122x150.jpg 122w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"837\" height=\"1024\" data-id=\"8470\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-837x1024.jpg\" alt=\"\" class=\"wp-image-8470\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-837x1024.jpg 837w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-245x300.jpg 245w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-768x940.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-1255x1536.jpg 1255w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-1673x2048.jpg 1673w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-9-1-123x150.jpg 123w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"839\" height=\"1024\" data-id=\"8471\" src=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-839x1024.jpg\" alt=\"\" class=\"wp-image-8471\" srcset=\"http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-839x1024.jpg 839w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-246x300.jpg 246w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-768x938.jpg 768w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-1258x1536.jpg 1258w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-1678x2048.jpg 1678w, http:\/\/quelaines-stemarie.fr\/wp-content\/uploads\/CE2-Celine-13-1-123x150.jpg 123w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ann\u00e9e scolaire touche \u00e0 sa fin. Voici les derni\u00e8res r\u00e9alisations de cette p\u00e9riode. Travail sur les d\u00e9grad\u00e9s de couleurs: Travail sur les couleurs compl\u00e9mentaires: Travail sur les nuances de bleu + d\u00e9couverte de l&#8217;artiste Aldemir Martins: D\u00e9couverte de l&#8217;artiste Vassily Kandinsky, avec diff\u00e9rentes &#8220;\u00e9tudes de couleurs&#8221;: D\u00e9couverte de l&#8217;Art Aborig\u00e8ne:<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"http:\/\/quelaines-stemarie.fr\/index.php\/2022\/06\/22\/arts-visuels-en-ce-cm-periode-5\/\">Lire la suite&#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,239],"tags":[],"class_list":["post-8380","post","type-post","status-publish","format-standard","hentry","category-cat-actualites","category-arts-visuels-avec-sylvie-a"],"_links":{"self":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/8380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=8380"}],"version-history":[{"count":2,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/8380\/revisions"}],"predecessor-version":[{"id":8472,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/8380\/revisions\/8472"}],"wp:attachment":[{"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=8380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=8380"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/quelaines-stemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=8380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}